{"id":5403,"date":"2020-06-03T10:05:57","date_gmt":"2020-06-03T08:05:57","guid":{"rendered":"https:\/\/cabtutela.it\/?p=5403"},"modified":"2020-06-03T10:05:57","modified_gmt":"2020-06-03T08:05:57","slug":"bollette-luce-e-gas-prescrizione-scende-a-due-anni-in-ogni-caso","status":"publish","type":"post","link":"https:\/\/cabtutela.it\/ita\/bollette-luce-e-gas-prescrizione-scende-a-due-anni-in-ogni-caso\/","title":{"rendered":"Bollette luce e gas, prescrizione scende a due anni in ogni caso"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>Stop ai maxi conguagli<\/strong> nelle bollette relativi a consumi di molti anni fa. Ora per gli operatori non sar\u00e0 possibile richiedere gli addebiti in nessun caso.<\/p>\n<p style=\"text-align: justify\">L\u2019Arera ha stabilito che dal 1 gennaio 2020 i clienti di energia e gas e gli utenti del servizio idrico, appartenenti alle tipologie indicate dalla legge e dalla regolazione vigente integrato possono \u201cin ogni caso\u201d eccepire la prescrizione per importi fatturati relativi ai consumi pi\u00f9 vecchi di 2 anni.<\/p>\n<p style=\"text-align: justify\">La novit\u00e0 era stata introdotta dalla Legge di bilancio 2020 (n. 160 del 2019), e negli scorsi giorni \u00e8 stata integrata da Arera nel quadro regolatorio complessivo, adeguando l\u2019informativa ai clienti e agli utenti che venditori e gestori devono inserire all\u2019interno delle fatture, anche in caso di procedure di messa in mora, nonch\u00e9 in caso di risposta ai reclami scritti dei clienti e degli utenti in merito.<\/p>\n<p style=\"text-align: justify\"><strong>I casi in cui veniva esclusa la prescrizione<br \/>\n<\/strong><br \/>\nPrima della novit\u00e0 normativa introdotta dalla Legge di bilancio 2020, si legge in una nota dell\u2019Autorit\u00e0, la prescrizione per i consumi relativi a periodi superiori ai 2 anni veniva esclusa nei casi in cui la mancata o erronea rilevazione dei relativi dati derivasse da un\u2019accertata responsabilit\u00e0 dell\u2019utente.<\/p>\n<p style=\"text-align: justify\">Per garantire la trasparenza, i venditori e i gestori erano gi\u00e0 tenuti a emettere una fattura separata contenente esclusivamente gli importi per consumi risalenti a pi\u00f9 di 2 anni oppure \u2013 in alternativa \u2013 ad evidenziare tali importi in modo chiaro e comprensibile all\u2019interno di fatture che contenessero anche importi non prescrivibili. I venditori e i gestori sono tenuti, in ogni caso, ad informare i clienti e gli utenti della possibilit\u00e0 di eccepire gli importi pi\u00f9 vecchi di due anni, fornendo un modulo che faciliti la comunicazione della volont\u00e0 di eccepire la prescrizione (da rendere disponibile anche su sito internet e negli sportelli al pubblico) e i recapiti cui inviare la richiesta.<\/p>\n<p>Articolo: <a href=\"https:\/\/quifinanza.it\/soldi\/bollette-luce-e-gas-prescrizione-scende-a-due-anni-in-ogni-caso\/387464\/\">QuiFinanza.it<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stop ai maxi conguagli nelle bollette relativi a consumi di molti anni fa. Ora per gli operatori non sar\u00e0 possibile richiedere gli addebiti in&#8230;<\/p>\n","protected":false},"author":2,"featured_media":5351,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[44],"tags":[],"class_list":["post-5403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"acf":[],"_links":{"self":[{"href":"https:\/\/cabtutela.it\/ita\/wp-json\/wp\/v2\/posts\/5403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cabtutela.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cabtutela.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cabtutela.it\/ita\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cabtutela.it\/ita\/wp-json\/wp\/v2\/comments?post=5403"}],"version-history":[{"count":0,"href":"https:\/\/cabtutela.it\/ita\/wp-json\/wp\/v2\/posts\/5403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cabtutela.it\/ita\/wp-json\/wp\/v2\/media\/5351"}],"wp:attachment":[{"href":"https:\/\/cabtutela.it\/ita\/wp-json\/wp\/v2\/media?parent=5403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cabtutela.it\/ita\/wp-json\/wp\/v2\/categories?post=5403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cabtutela.it\/ita\/wp-json\/wp\/v2\/tags?post=5403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}